{"id":678485,"date":"2022-08-25T11:27:52","date_gmt":"2022-08-25T02:27:52","guid":{"rendered":"https:\/\/www.marketreport.jp\/research\/?p=678485"},"modified":"2026-07-21T18:16:04","modified_gmt":"2026-07-21T09:16:04","slug":"global-laparoscopic-morcellators-market-research-report-girc-078950","status":"publish","type":"post","link":"https:\/\/www.marketreport.jp\/research\/global-laparoscopic-morcellators-market-research-report-girc-078950","title":{"rendered":"\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u4e16\u754c\u5e02\u5834\uff082026\u5e74\u7248\uff09"},"content":{"rendered":"<table width='100%' border='1px'>\n<tr>\n<td>\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u4e16\u754c\u5e02\u5834\u30ec\u30dd\u30fc\u30c8\uff08Global Laparoscopic Morcellators Market\uff09\u3067\u306f\u3001\u30bb\u30b0\u30e1\u30f3\u30c8\u5225\u5e02\u5834\u898f\u6a21\u3001\u4e3b\u8981\u5730\u57df\u3068\u56fd\u5225\u5e02\u5834\u898f\u6a21\u3001\u56fd\u5185\u5916\u306e\u4e3b\u8981\u30d7\u30ec\u30fc\u30e4\u30fc\u306e\u52d5\u5411\u3068\u5e02\u5834\u30b7\u30a7\u30a2\u3001\u8ca9\u58f2\u30c1\u30e3\u30cd\u30eb\u306a\u3069\u306e\u9805\u76ee\u306b\u3064\u3044\u3066\u8a73\u7d30\u306a\u5206\u6790\u3092\u884c\u3044\u307e\u3057\u305f\u3002<\/p>\n<p>\u6700\u65b0\u306e\u8abf\u67fb\u306b\u3088\u308b\u3068\u3001\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u4e16\u754c\u5e02\u5834\u898f\u6a21\u306f\u30012025\u5e74\u306exxx\u767e\u4e07\u30c9\u30eb\u304b\u30892026\u5e74\u306b\u306fxxx\u767e\u4e07\u30c9\u30eb\u3068\u306a\u308a\u30012025\u5e74\u304b\u30892026\u5e74\u306e\u9593\u306bxx\uff05\u306e\u5909\u5316\u304c\u3042\u308b\u3068\u63a8\u5b9a\u3055\u308c\u3066\u3044\u307e\u3059\u3002\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u4e16\u754c\u5e02\u5834\u898f\u6a21\u306f\u3001\u4eca\u5f8c5\u5e74\u9593\u3067xx\uff05\u306e\u5e74\u7387\u3067\u6210\u9577\u3059\u308b\u3068\u4e88\u6e2c\u3055\u308c\u3066\u3044\u307e\u3059\u3002<\/p>\n<p>\u5730\u57df\u30fb\u56fd\u5225\u5206\u6790\u3067\u306f\u3001\u5317\u7c73\u3001\u30a2\u30e1\u30ea\u30ab\u3001\u30ab\u30ca\u30c0\u3001\u30e1\u30ad\u30b7\u30b3\u3001\u30e8\u30fc\u30ed\u30c3\u30d1\u3001\u30c9\u30a4\u30c4\u3001\u30a4\u30ae\u30ea\u30b9\u3001\u30d5\u30e9\u30f3\u30b9\u3001\u30ed\u30b7\u30a2\u3001\u30a2\u30b8\u30a2\u592a\u5e73\u6d0b\u3001\u65e5\u672c\u3001\u4e2d\u56fd\u3001\u30a4\u30f3\u30c9\u3001\u97d3\u56fd\u3001\u6771\u5357\u30a2\u30b8\u30a2\u3001\u5357\u7c73\u3001\u4e2d\u6771\u3001\u30a2\u30d5\u30ea\u30ab\u306a\u3069\u3092\u5bfe\u8c61\u306b\u3057\u3066\u3001\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u5e02\u5834\u898f\u6a21\u3092\u7b97\u51fa\u3057\u307e\u3057\u305f\u3002<\/p>\n<p>\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u306f\u3001\u7a2e\u985e\u5225\u306b\u306f\u3001\u96fb\u6c17\u6a5f\u68b0\u5f0f\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u3001\u30d0\u30a4\u30dd\u30fc\u30e9\u5f0f\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306b\u3001\u7528\u9014\u5225\u306b\u306f\u3001\u8179\u8154\u93e1\u4e0b\u5b50\u5bae\u6458\u51fa\u8853\u3001\u8179\u8154\u93e1\u4e0b\u80c6\u56a2\u6458\u51fa\u8853\u3001\u8179\u8154\u93e1\u4e0b\u814e\u81d3\u6458\u51fa\u8853\u306b\u533a\u5206\u3057\u3066\u30b0\u30ed\u30fc\u30d0\u30eb\u3068\u4e3b\u8981\u5730\u57df\u306b\u304a\u3051\u308b2021\u5e74\uff5e2031\u5e74\u306e\u5e02\u5834\u898f\u6a21\u3092\u8abf\u67fb\u30fb\u4e88\u6e2c\u3057\u307e\u3057\u305f\u3002<\/p>\n<p>\u5f53\u30ec\u30dd\u30fc\u30c8\u306b\u542b\u307e\u308c\u308b\u4e3b\u8981\u4f01\u696d\u306f\u3001Ethicon\u3001 Medtronic\u3001 Karl Storz\u3001&#8230;\u306a\u3069\u304c\u3042\u308a\u3001\u5404\u4f01\u696d\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u8ca9\u58f2\u91cf\u3001\u58f2\u4e0a\u3001\u4fa1\u683c\u3001\u5e02\u5834\u30b7\u30a7\u30a2\u306a\u3069\u3092\u5206\u6790\u3057\u307e\u3057\u305f\u3002<\/p>\n<p><strong>\u3010\u76ee\u6b21\u3011<\/strong><\/p>\n<p>\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u306e\u6982\u8981\uff08Global Laparoscopic Morcellators Market\uff09<\/p>\n<p>\u4e3b\u8981\u4f01\u696d\u306e\u52d5\u5411<br \/>\n&#8211; Ethicon\u793e\u306e\u4f01\u696d\u6982\u8981\u30fb\u88fd\u54c1\u6982\u8981<br \/>\n&#8211; Ethicon\u793e\u306e\u8ca9\u58f2\u91cf\u30fb\u58f2\u4e0a\u30fb\u4fa1\u683c\u30fb\u5e02\u5834\u30b7\u30a7\u30a2<br \/>\n&#8211; Ethicon\u793e\u306e\u4e8b\u696d\u52d5\u5411<br \/>\n&#8211;  Medtronic\u793e\u306e\u4f01\u696d\u6982\u8981\u30fb\u88fd\u54c1\u6982\u8981<br \/>\n&#8211;  Medtronic\u793e\u306e\u8ca9\u58f2\u91cf\u30fb\u58f2\u4e0a\u30fb\u4fa1\u683c\u30fb\u5e02\u5834\u30b7\u30a7\u30a2<br \/>\n&#8211;  Medtronic\u793e\u306e\u4e8b\u696d\u52d5\u5411<br \/>\n&#8211;  Karl Storz\u793e\u306e\u4f01\u696d\u6982\u8981\u30fb\u88fd\u54c1\u6982\u8981<br \/>\n&#8211;  Karl Storz\u793e\u306e\u8ca9\u58f2\u91cf\u30fb\u58f2\u4e0a\u30fb\u4fa1\u683c\u30fb\u5e02\u5834\u30b7\u30a7\u30a2<br \/>\n&#8211;  Karl Storz\u793e\u306e\u4e8b\u696d\u52d5\u5411<br \/>\n  &#8230;<br \/>\n  &#8230;<br \/>\n\u4f01\u696d\u5225\u58f2\u4e0a\u53ca\u3073\u5e02\u5834\u30b7\u30a7\u30a2\uff08\uff5e2026\u5e74\uff09<\/p>\n<p>\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u4e16\u754c\u5e02\u5834\uff082021\u5e74\uff5e2031\u5e74\uff09<br \/>\n&#8211; \u7a2e\u985e\u5225\u533a\u5206\uff1a\u96fb\u6c17\u6a5f\u68b0\u5f0f\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u3001\u30d0\u30a4\u30dd\u30fc\u30e9\u5f0f\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf<br \/>\n&#8211; \u7a2e\u985e\u5225\u5e02\u5834\u898f\u6a21\uff08\u8ca9\u58f2\u91cf\u30fb\u58f2\u4e0a\u30fb\u4fa1\u683c\uff09<br \/>\n&#8211; \u7528\u9014\u5225\u533a\u5206\uff1a\u8179\u8154\u93e1\u4e0b\u5b50\u5bae\u6458\u51fa\u8853\u3001\u8179\u8154\u93e1\u4e0b\u80c6\u56a2\u6458\u51fa\u8853\u3001\u8179\u8154\u93e1\u4e0b\u814e\u81d3\u6458\u51fa\u8853<br \/>\n&#8211; \u7528\u9014\u5225\u5e02\u5834\u898f\u6a21\uff08\u8ca9\u58f2\u91cf\u30fb\u58f2\u4e0a\u30fb\u4fa1\u683c\uff09<\/p>\n<p>\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u5730\u57df\u5225\u5e02\u5834\u5206\u6790<\/p>\n<p>\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u5317\u7c73\u5e02\u5834\uff082021\u5e74\uff5e2031\u5e74\uff09<br \/>\n&#8211; \u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u5317\u7c73\u5e02\u5834\uff1a\u7a2e\u985e\u5225<br \/>\n&#8211; \u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u5317\u7c73\u5e02\u5834\uff1a\u7528\u9014\u5225<br \/>\n&#8211; \u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u30a2\u30e1\u30ea\u30ab\u5e02\u5834\u898f\u6a21<br \/>\n&#8211; \u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u30ab\u30ca\u30c0\u5e02\u5834\u898f\u6a21<br \/>\n&#8211; \u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u30e1\u30ad\u30b7\u30b3\u5e02\u5834\u898f\u6a21<br \/>\n&#8230;<\/p>\n<p>\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u30e8\u30fc\u30ed\u30c3\u30d1\u5e02\u5834\uff082021\u5e74\uff5e2031\u5e74\uff09<br \/>\n&#8211; \u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u30e8\u30fc\u30ed\u30c3\u30d1\u5e02\u5834\uff1a\u7a2e\u985e\u5225<br \/>\n&#8211; \u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u30e8\u30fc\u30ed\u30c3\u30d1\u5e02\u5834\uff1a\u7528\u9014\u5225<br \/>\n&#8211; \u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u30c9\u30a4\u30c4\u5e02\u5834\u898f\u6a21<br \/>\n&#8211; \u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u30a4\u30ae\u30ea\u30b9\u5e02\u5834\u898f\u6a21<br \/>\n&#8211; \u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u30d5\u30e9\u30f3\u30b9\u5e02\u5834\u898f\u6a21<br \/>\n&#8230;<\/p>\n<p>\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u30a2\u30b8\u30a2\u5e02\u5834\uff082021\u5e74\uff5e2031\u5e74\uff09<br \/>\n&#8211; \u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u30a2\u30b8\u30a2\u5e02\u5834\uff1a\u7a2e\u985e\u5225<br \/>\n&#8211; \u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u30a2\u30b8\u30a2\u5e02\u5834\uff1a\u7528\u9014\u5225<br \/>\n&#8211; \u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u65e5\u672c\u5e02\u5834\u898f\u6a21<br \/>\n&#8211; \u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u4e2d\u56fd\u5e02\u5834\u898f\u6a21<br \/>\n&#8211; \u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u30a4\u30f3\u30c9\u5e02\u5834\u898f\u6a21<br \/>\n&#8211; \u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u6771\u5357\u30a2\u30b8\u30a2\u5e02\u5834\u898f\u6a21<br \/>\n&#8230;<\/p>\n<p>\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u5357\u7c73\u5e02\u5834\uff082021\u5e74\uff5e2031\u5e74\uff09<br \/>\n&#8211; \u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u5357\u7c73\u5e02\u5834\uff1a\u7a2e\u985e\u5225<br \/>\n&#8211; \u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u5357\u7c73\u5e02\u5834\uff1a\u7528\u9014\u5225<br \/>\n&#8230;<\/p>\n<p>\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u4e2d\u6771\u30fb\u30a2\u30d5\u30ea\u30ab\u5e02\u5834\uff082021\u5e74\uff5e2031\u5e74\uff09<br \/>\n&#8211; \u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u4e2d\u6771\u30fb\u30a2\u30d5\u30ea\u30ab\u5e02\u5834\uff1a\u7a2e\u985e\u5225<br \/>\n&#8211; \u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u4e2d\u6771\u30fb\u30a2\u30d5\u30ea\u30ab\u5e02\u5834\uff1a\u7528\u9014\u5225<br \/>\n&#8230;<\/p>\n<p>\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u8ca9\u58f2\u30c1\u30e3\u30cd\u30eb\u5206\u6790<\/p>\n<p>\u8abf\u67fb\u306e\u7d50\u8ad6<\/td>\n<\/tr>\n<\/table>\n<p><span style='color:royalblue; font-size:0.9em;'>\u203b\u5f0a\u793e\u3067\u306f\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u3092\u5bfe\u8c61\u306b\u7279\u5b9a\u306e\u5730\u57df\u306b\u7d5e\u3063\u305f\u30ab\u30b9\u30bf\u30e0\u30ec\u30dd\u30fc\u30c8\u3082\u8ca9\u58f2\u3057\u3066\u3044\u307e\u3059\u3002<\/span><\/p>\n<table width='100%' border='1px'>\n<tr>\n<td>\n\u3010\u30a2\u30b8\u30a2\u592a\u5e73\u6d0b\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u30ec\u30dd\u30fc\u30c8\uff08\u8cc7\u6599\u30b3\u30fc\u30c9\uff1aGIRC-078950-AP\uff09\u3011<\/p>\n<p>\u672c\u8abf\u67fb\u8cc7\u6599\u306f\u30a2\u30b8\u30a2\u592a\u5e73\u6d0b\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u306b\u3064\u3044\u3066\u8abf\u67fb\u30fb\u5206\u6790\u3057\u3001\u5e02\u5834\u6982\u8981\u3001\u5e02\u5834\u52d5\u5411\u3001\u5e02\u5834\u898f\u6a21\u3001\u5e02\u5834\u4e88\u6e2c\u3001\u5e02\u5834\u30b7\u30a7\u30a2\u3001\u4f01\u696d\u60c5\u5831\u306a\u3069\u3092\u63b2\u8f09\u3057\u3066\u3044\u307e\u3059\u3002\u30a2\u30b8\u30a2\u592a\u5e73\u6d0b\u5730\u57df\u306b\u304a\u3051\u308b\u7a2e\u985e\u5225\uff08\u96fb\u6c17\u6a5f\u68b0\u5f0f\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u3001\u30d0\u30a4\u30dd\u30fc\u30e9\u5f0f\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\uff09\u5e02\u5834\u898f\u6a21\u3068\u7528\u9014\u5225\uff08\u8179\u8154\u93e1\u4e0b\u5b50\u5bae\u6458\u51fa\u8853\u3001\u8179\u8154\u93e1\u4e0b\u80c6\u56a2\u6458\u51fa\u8853\u3001\u8179\u8154\u93e1\u4e0b\u814e\u81d3\u6458\u51fa\u8853\uff09\u5e02\u5834\u898f\u6a21\u3001\u4e3b\u8981\u56fd\u5225\uff08\u65e5\u672c\u3001\u4e2d\u56fd\u3001\u97d3\u56fd\u3001\u30a4\u30f3\u30c9\u3001\u30aa\u30fc\u30b9\u30c8\u30e9\u30ea\u30a2\u3001\u6771\u5357\u30a2\u30b8\u30a2\u306a\u3069\uff09\u5e02\u5834\u898f\u6a21\u30c7\u30fc\u30bf\u3082\u542b\u307e\u308c\u3066\u3044\u307e\u3059\u3002\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u30a2\u30b8\u30a2\u592a\u5e73\u6d0b\u5e02\u5834\u30ec\u30dd\u30fc\u30c8\u306f2026\u5e74\u82f1\u8a9e\u7248\u3067\u3001\u4e00\u90e8\u30ab\u30b9\u30bf\u30de\u30a4\u30ba\u3082\u53ef\u80fd\u3067\u3059\u3002<\/p>\n<p>\u30fb\u30a2\u30b8\u30a2\u592a\u5e73\u6d0b\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u6982\u8981<br \/>\n\u30fb\u30a2\u30b8\u30a2\u592a\u5e73\u6d0b\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u52d5\u5411<br \/>\n\u30fb\u30a2\u30b8\u30a2\u592a\u5e73\u6d0b\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u898f\u6a21<br \/>\n\u30fb\u30a2\u30b8\u30a2\u592a\u5e73\u6d0b\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u4e88\u6e2c<br \/>\n\u30fb\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u7a2e\u985e\u5225\u5e02\u5834\u5206\u6790<br \/>\n\u30fb\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u7528\u9014\u5225\u5e02\u5834\u5206\u6790<br \/>\n\u30fb\u4e3b\u8981\u56fd\u5225\u5e02\u5834\u898f\u6a21\uff08\u65e5\u672c\u3001\u4e2d\u56fd\u3001\u97d3\u56fd\u3001\u30a4\u30f3\u30c9\u3001\u30aa\u30fc\u30b9\u30c8\u30e9\u30ea\u30a2\u3001\u6771\u5357\u30a2\u30b8\u30a2\u306a\u3069\uff09<br \/>\n\u30fb\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u4e3b\u8981\u4f01\u696d\u5206\u6790(\u4f01\u696d\u60c5\u5831\u3001\u58f2\u4e0a\u3001\u5e02\u5834\u30b7\u30a7\u30a2\u306a\u3069)\n<\/td>\n<\/tr>\n<\/table>\n<table width='100%' border='1px'>\n<tr>\n<td>\n\u3010\u6771\u5357\u30a2\u30b8\u30a2\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u30ec\u30dd\u30fc\u30c8\uff08\u8cc7\u6599\u30b3\u30fc\u30c9\uff1aGIRC-078950-SA\uff09\u3011<\/p>\n<p>\u672c\u8abf\u67fb\u8cc7\u6599\u306f\u6771\u5357\u30a2\u30b8\u30a2\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u306b\u3064\u3044\u3066\u8abf\u67fb\u30fb\u5206\u6790\u3057\u3001\u5e02\u5834\u6982\u8981\u3001\u5e02\u5834\u52d5\u5411\u3001\u5e02\u5834\u898f\u6a21\u3001\u5e02\u5834\u4e88\u6e2c\u3001\u5e02\u5834\u30b7\u30a7\u30a2\u3001\u4f01\u696d\u60c5\u5831\u306a\u3069\u3092\u63b2\u8f09\u3057\u3066\u3044\u307e\u3059\u3002\u6771\u5357\u30a2\u30b8\u30a2\u5730\u57df\u306b\u304a\u3051\u308b\u7a2e\u985e\u5225\uff08\u96fb\u6c17\u6a5f\u68b0\u5f0f\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u3001\u30d0\u30a4\u30dd\u30fc\u30e9\u5f0f\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\uff09\u5e02\u5834\u898f\u6a21\u3068\u7528\u9014\u5225\uff08\u8179\u8154\u93e1\u4e0b\u5b50\u5bae\u6458\u51fa\u8853\u3001\u8179\u8154\u93e1\u4e0b\u80c6\u56a2\u6458\u51fa\u8853\u3001\u8179\u8154\u93e1\u4e0b\u814e\u81d3\u6458\u51fa\u8853\uff09\u5e02\u5834\u898f\u6a21\u3001\u4e3b\u8981\u56fd\u5225\uff08\u30a4\u30f3\u30c9\u30cd\u30b7\u30a2\u3001\u30de\u30ec\u30fc\u30b7\u30a2\u3001\u30d5\u30a3\u30ea\u30d4\u30f3\u3001\u30b7\u30f3\u30ac\u30dd\u30fc\u30eb\u3001\u30bf\u30a4\u306a\u3069\uff09\u5e02\u5834\u898f\u6a21\u30c7\u30fc\u30bf\u3082\u542b\u307e\u308c\u3066\u3044\u307e\u3059\u3002\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u6771\u5357\u30a2\u30b8\u30a2\u5e02\u5834\u30ec\u30dd\u30fc\u30c8\u306f2026\u5e74\u82f1\u8a9e\u7248\u3067\u3001\u4e00\u90e8\u30ab\u30b9\u30bf\u30de\u30a4\u30ba\u3082\u53ef\u80fd\u3067\u3059\u3002<\/p>\n<p>\u30fb\u6771\u5357\u30a2\u30b8\u30a2\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u6982\u8981<br \/>\n\u30fb\u6771\u5357\u30a2\u30b8\u30a2\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u52d5\u5411<br \/>\n\u30fb\u6771\u5357\u30a2\u30b8\u30a2\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u898f\u6a21<br \/>\n\u30fb\u6771\u5357\u30a2\u30b8\u30a2\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u4e88\u6e2c<br \/>\n\u30fb\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u7a2e\u985e\u5225\u5e02\u5834\u5206\u6790<br \/>\n\u30fb\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u7528\u9014\u5225\u5e02\u5834\u5206\u6790<br \/>\n\u30fb\u4e3b\u8981\u56fd\u5225\u5e02\u5834\u898f\u6a21\uff08\u30a4\u30f3\u30c9\u30cd\u30b7\u30a2\u3001\u30de\u30ec\u30fc\u30b7\u30a2\u3001\u30d5\u30a3\u30ea\u30d4\u30f3\u3001\u30b7\u30f3\u30ac\u30dd\u30fc\u30eb\u3001\u30bf\u30a4\u306a\u3069\uff09<br \/>\n\u30fb\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u4e3b\u8981\u4f01\u696d\u5206\u6790(\u4f01\u696d\u60c5\u5831\u3001\u58f2\u4e0a\u3001\u5e02\u5834\u30b7\u30a7\u30a2\u306a\u3069)\n<\/td>\n<\/tr>\n<\/table>\n<table width='100%' border='1px'>\n<tr>\n<td>\n\u3010\u30e8\u30fc\u30ed\u30c3\u30d1\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u30ec\u30dd\u30fc\u30c8\uff08\u8cc7\u6599\u30b3\u30fc\u30c9\uff1aGIRC-078950-EU\uff09\u3011<\/p>\n<p>\u672c\u8abf\u67fb\u8cc7\u6599\u306f\u30e8\u30fc\u30ed\u30c3\u30d1\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u306b\u3064\u3044\u3066\u8abf\u67fb\u30fb\u5206\u6790\u3057\u3001\u5e02\u5834\u6982\u8981\u3001\u5e02\u5834\u52d5\u5411\u3001\u5e02\u5834\u898f\u6a21\u3001\u5e02\u5834\u4e88\u6e2c\u3001\u5e02\u5834\u30b7\u30a7\u30a2\u3001\u4f01\u696d\u60c5\u5831\u306a\u3069\u3092\u63b2\u8f09\u3057\u3066\u3044\u307e\u3059\u3002\u30e8\u30fc\u30ed\u30c3\u30d1\u5730\u57df\u306b\u304a\u3051\u308b\u7a2e\u985e\u5225\uff08\u96fb\u6c17\u6a5f\u68b0\u5f0f\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u3001\u30d0\u30a4\u30dd\u30fc\u30e9\u5f0f\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\uff09\u5e02\u5834\u898f\u6a21\u3068\u7528\u9014\u5225\uff08\u8179\u8154\u93e1\u4e0b\u5b50\u5bae\u6458\u51fa\u8853\u3001\u8179\u8154\u93e1\u4e0b\u80c6\u56a2\u6458\u51fa\u8853\u3001\u8179\u8154\u93e1\u4e0b\u814e\u81d3\u6458\u51fa\u8853\uff09\u5e02\u5834\u898f\u6a21\u3001\u4e3b\u8981\u56fd\u5225\uff08\u30c9\u30a4\u30c4\u3001\u30d5\u30e9\u30f3\u30b9\u3001\u30a4\u30ae\u30ea\u30b9\u3001\u30a4\u30bf\u30ea\u30a2\u3001\u30ed\u30b7\u30a2\u306a\u3069\uff09\u5e02\u5834\u898f\u6a21\u30c7\u30fc\u30bf\u3082\u542b\u307e\u308c\u3066\u3044\u307e\u3059\u3002\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u30e8\u30fc\u30ed\u30c3\u30d1\u5e02\u5834\u30ec\u30dd\u30fc\u30c8\u306f2026\u5e74\u82f1\u8a9e\u7248\u3067\u3001\u4e00\u90e8\u30ab\u30b9\u30bf\u30de\u30a4\u30ba\u3082\u53ef\u80fd\u3067\u3059\u3002<\/p>\n<p>\u30fb\u30e8\u30fc\u30ed\u30c3\u30d1\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u6982\u8981<br \/>\n\u30fb\u30e8\u30fc\u30ed\u30c3\u30d1\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u52d5\u5411<br \/>\n\u30fb\u30e8\u30fc\u30ed\u30c3\u30d1\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u898f\u6a21<br \/>\n\u30fb\u30e8\u30fc\u30ed\u30c3\u30d1\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u4e88\u6e2c<br \/>\n\u30fb\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u7a2e\u985e\u5225\u5e02\u5834\u5206\u6790<br \/>\n\u30fb\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u7528\u9014\u5225\u5e02\u5834\u5206\u6790<br \/>\n\u30fb\u4e3b\u8981\u56fd\u5225\u5e02\u5834\u898f\u6a21\uff1a\u30c9\u30a4\u30c4\u3001\u30d5\u30e9\u30f3\u30b9\u3001\u30a4\u30ae\u30ea\u30b9\u3001\u30a4\u30bf\u30ea\u30a2\u3001\u30ed\u30b7\u30a2\u306a\u3069<br \/>\n\u30fb\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u4e3b\u8981\u4f01\u696d\u5206\u6790(\u4f01\u696d\u60c5\u5831\u3001\u58f2\u4e0a\u3001\u5e02\u5834\u30b7\u30a7\u30a2\u306a\u3069)\n<\/td>\n<\/tr>\n<\/table>\n<table width='100%' border='1px'>\n<tr>\n<td>\n\u3010\u30a2\u30e1\u30ea\u30ab\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u30ec\u30dd\u30fc\u30c8\uff08\u8cc7\u6599\u30b3\u30fc\u30c9\uff1aGIRC-078950-US\uff09\u3011<\/p>\n<p>\u672c\u8abf\u67fb\u8cc7\u6599\u306f\u30a2\u30e1\u30ea\u30ab\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u306b\u3064\u3044\u3066\u8abf\u67fb\u30fb\u5206\u6790\u3057\u3001\u5e02\u5834\u6982\u8981\u3001\u5e02\u5834\u52d5\u5411\u3001\u5e02\u5834\u898f\u6a21\u3001\u5e02\u5834\u4e88\u6e2c\u3001\u5e02\u5834\u30b7\u30a7\u30a2\u3001\u4f01\u696d\u60c5\u5831\u306a\u3069\u3092\u63b2\u8f09\u3057\u3066\u3044\u307e\u3059\u3002\u30a2\u30e1\u30ea\u30ab\u306b\u304a\u3051\u308b\u7a2e\u985e\u5225\uff08\u96fb\u6c17\u6a5f\u68b0\u5f0f\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u3001\u30d0\u30a4\u30dd\u30fc\u30e9\u5f0f\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\uff09\u5e02\u5834\u898f\u6a21\u3068\u7528\u9014\u5225\uff08\u8179\u8154\u93e1\u4e0b\u5b50\u5bae\u6458\u51fa\u8853\u3001\u8179\u8154\u93e1\u4e0b\u80c6\u56a2\u6458\u51fa\u8853\u3001\u8179\u8154\u93e1\u4e0b\u814e\u81d3\u6458\u51fa\u8853\uff09\u5e02\u5834\u898f\u6a21\u30c7\u30fc\u30bf\u3082\u542b\u307e\u308c\u3066\u3044\u307e\u3059\u3002\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u30a2\u30e1\u30ea\u30ab\u5e02\u5834\u30ec\u30dd\u30fc\u30c8\u306f2026\u5e74\u82f1\u8a9e\u7248\u3067\u3001\u4e00\u90e8\u30ab\u30b9\u30bf\u30de\u30a4\u30ba\u3082\u53ef\u80fd\u3067\u3059\u3002<\/p>\n<p>\u30fb\u30a2\u30e1\u30ea\u30ab\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u6982\u8981<br \/>\n\u30fb\u30a2\u30e1\u30ea\u30ab\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u52d5\u5411<br \/>\n\u30fb\u30a2\u30e1\u30ea\u30ab\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u898f\u6a21<br \/>\n\u30fb\u30a2\u30e1\u30ea\u30ab\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u4e88\u6e2c<br \/>\n\u30fb\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u7a2e\u985e\u5225\u5e02\u5834\u5206\u6790<br \/>\n\u30fb\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u7528\u9014\u5225\u5e02\u5834\u5206\u6790<br \/>\n\u30fb\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u4e3b\u8981\u4f01\u696d\u5206\u6790(\u4f01\u696d\u60c5\u5831\u3001\u58f2\u4e0a\u3001\u5e02\u5834\u30b7\u30a7\u30a2\u306a\u3069)\n<\/td>\n<\/tr>\n<\/table>\n<table width='100%' border='1px'>\n<tr>\n<td>\n\u3010\u4e2d\u56fd\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u30ec\u30dd\u30fc\u30c8\uff08\u8cc7\u6599\u30b3\u30fc\u30c9\uff1aGIRC-078950-CN\uff09\u3011<\/p>\n<p>\u672c\u8abf\u67fb\u8cc7\u6599\u306f\u4e2d\u56fd\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u306b\u3064\u3044\u3066\u8abf\u67fb\u30fb\u5206\u6790\u3057\u3001\u5e02\u5834\u6982\u8981\u3001\u5e02\u5834\u52d5\u5411\u3001\u5e02\u5834\u898f\u6a21\u3001\u5e02\u5834\u4e88\u6e2c\u3001\u5e02\u5834\u30b7\u30a7\u30a2\u3001\u4f01\u696d\u60c5\u5831\u306a\u3069\u3092\u63b2\u8f09\u3057\u3066\u3044\u307e\u3059\u3002\u4e2d\u56fd\u306b\u304a\u3051\u308b\u7a2e\u985e\u5225\uff08\u96fb\u6c17\u6a5f\u68b0\u5f0f\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u3001\u30d0\u30a4\u30dd\u30fc\u30e9\u5f0f\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\uff09\u5e02\u5834\u898f\u6a21\u3068\u7528\u9014\u5225\uff08\u8179\u8154\u93e1\u4e0b\u5b50\u5bae\u6458\u51fa\u8853\u3001\u8179\u8154\u93e1\u4e0b\u80c6\u56a2\u6458\u51fa\u8853\u3001\u8179\u8154\u93e1\u4e0b\u814e\u81d3\u6458\u51fa\u8853\uff09\u5e02\u5834\u898f\u6a21\u30c7\u30fc\u30bf\u3082\u542b\u307e\u308c\u3066\u3044\u307e\u3059\u3002\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u4e2d\u56fd\u5e02\u5834\u30ec\u30dd\u30fc\u30c8\u306f2026\u5e74\u82f1\u8a9e\u7248\u3067\u3001\u4e00\u90e8\u30ab\u30b9\u30bf\u30de\u30a4\u30ba\u3082\u53ef\u80fd\u3067\u3059\u3002<\/p>\n<p>\u30fb\u4e2d\u56fd\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u6982\u8981<br \/>\n\u30fb\u4e2d\u56fd\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u52d5\u5411<br \/>\n\u30fb\u4e2d\u56fd\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u898f\u6a21<br \/>\n\u30fb\u4e2d\u56fd\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u4e88\u6e2c<br \/>\n\u30fb\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u7a2e\u985e\u5225\u5e02\u5834\u5206\u6790<br \/>\n\u30fb\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u7528\u9014\u5225\u5e02\u5834\u5206\u6790<br \/>\n\u30fb\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u4e3b\u8981\u4f01\u696d\u5206\u6790(\u4f01\u696d\u60c5\u5831\u3001\u58f2\u4e0a\u3001\u5e02\u5834\u30b7\u30a7\u30a2\u306a\u3069)\n<\/td>\n<\/tr>\n<\/table>\n<table width='100%' border='1px'>\n<tr>\n<td>\n\u3010\u30a4\u30f3\u30c9\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u30ec\u30dd\u30fc\u30c8\uff08\u8cc7\u6599\u30b3\u30fc\u30c9\uff1aGIRC-078950-IN\uff09\u3011<\/p>\n<p>\u672c\u8abf\u67fb\u8cc7\u6599\u306f\u30a4\u30f3\u30c9\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u306b\u3064\u3044\u3066\u8abf\u67fb\u30fb\u5206\u6790\u3057\u3001\u5e02\u5834\u6982\u8981\u3001\u5e02\u5834\u52d5\u5411\u3001\u5e02\u5834\u898f\u6a21\u3001\u5e02\u5834\u4e88\u6e2c\u3001\u5e02\u5834\u30b7\u30a7\u30a2\u3001\u4f01\u696d\u60c5\u5831\u306a\u3069\u3092\u63b2\u8f09\u3057\u3066\u3044\u307e\u3059\u3002\u30a4\u30f3\u30c9\u306b\u304a\u3051\u308b\u7a2e\u985e\u5225\uff08\u96fb\u6c17\u6a5f\u68b0\u5f0f\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u3001\u30d0\u30a4\u30dd\u30fc\u30e9\u5f0f\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\uff09\u5e02\u5834\u898f\u6a21\u3068\u7528\u9014\u5225\uff08\u8179\u8154\u93e1\u4e0b\u5b50\u5bae\u6458\u51fa\u8853\u3001\u8179\u8154\u93e1\u4e0b\u80c6\u56a2\u6458\u51fa\u8853\u3001\u8179\u8154\u93e1\u4e0b\u814e\u81d3\u6458\u51fa\u8853\uff09\u5e02\u5834\u898f\u6a21\u30c7\u30fc\u30bf\u3082\u542b\u307e\u308c\u3066\u3044\u307e\u3059\u3002\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u30a4\u30f3\u30c9\u5e02\u5834\u30ec\u30dd\u30fc\u30c8\u306f2026\u5e74\u82f1\u8a9e\u7248\u3067\u3001\u4e00\u90e8\u30ab\u30b9\u30bf\u30de\u30a4\u30ba\u3082\u53ef\u80fd\u3067\u3059\u3002<\/p>\n<p>\u30fb\u30a4\u30f3\u30c9\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u6982\u8981<br \/>\n\u30fb\u30a4\u30f3\u30c9\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u52d5\u5411<br \/>\n\u30fb\u30a4\u30f3\u30c9\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u898f\u6a21<br \/>\n\u30fb\u30a4\u30f3\u30c9\u306e\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u5e02\u5834\u4e88\u6e2c<br \/>\n\u30fb\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u7a2e\u985e\u5225\u5e02\u5834\u5206\u6790<br \/>\n\u30fb\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u7528\u9014\u5225\u5e02\u5834\u5206\u6790<br \/>\n\u30fb\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u4e3b\u8981\u4f01\u696d\u5206\u6790(\u4f01\u696d\u60c5\u5831\u3001\u58f2\u4e0a\u3001\u5e02\u5834\u30b7\u30a7\u30a2\u306a\u3069)<\/td>\n<\/tr>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u4e16\u754c\u5e02\u5834\u30ec\u30dd\u30fc\u30c8\uff08Global Laparoscopic Morcellators Market\uff09\u3067\u306f\u3001\u30bb\u30b0\u30e1\u30f3\u30c8\u5225\u5e02\u5834\u898f\u6a21\uff08\u7a2e\u985e\u5225\uff1a\u96fb\u6c17\u6a5f\u68b0\u5f0f\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u3001\u30d0\u30a4\u30dd\u30fc\u30e9\u5f0f\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u3001\u7528\u9014\u5225\uff1a\u8179\u8154\u93e1\u4e0b\u5b50\u5bae\u6458\u51fa\u8853\u3001\u8179\u8154\u93e1\u4e0b\u80c6\u56a2\u6458\u51fa\u8853\u3001\u8179\u8154\u93e1\u4e0b\u814e\u81d3\u6458\u51fa\u8853\uff09\u3001\u4e3b\u8981\u5730\u57df\u3068\u56fd\u5225\u5e02\u5834\u898f\u6a21\u3001\u56fd\u5185\u5916\u306e\u4e3b\u8981\u30d7\u30ec\u30fc\u30e4\u30fc\u306e\u52d5\u5411\u3068\u5e02\u5834\u30b7\u30a7\u30a2\u3001\u8ca9\u58f2\u30c1\u30e3\u30cd\u30eb\u306a\u3069\u306e\u9805\u76ee\u306b\u3064\u3044\u3066\u8a73\u7d30\u306a\u5206\u6790\u3092\u884c\u3044\u307e\u3057\u305f\u3002\u5730\u57df\u30fb\u56fd\u5225\u5206\u6790\u3067\u306f\u3001\u5317\u7c73\u3001\u30a2\u30e1\u30ea\u30ab\u3001\u30ab\u30ca\u30c0\u3001\u30e1\u30ad\u30b7\u30b3\u3001\u30e8\u30fc\u30ed\u30c3\u30d1\u3001\u30c9\u30a4\u30c4\u3001\u30a4\u30ae\u30ea\u30b9\u3001\u30d5\u30e9\u30f3\u30b9\u3001\u30ed\u30b7\u30a2\u3001\u30a2\u30b8\u30a2\u592a\u5e73\u6d0b\u3001\u65e5\u672c\u3001\u4e2d\u56fd\u3001\u30a4\u30f3\u30c9\u3001\u97d3\u56fd\u3001\u6771\u5357\u30a2\u30b8\u30a2\u3001\u5357\u7c73\u3001\u4e2d\u6771\u3001\u30a2\u30d5\u30ea\u30ab\u306a\u3069\u3092\u5bfe\u8c61\u306b\u3057\u3066\u3001\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u5e02\u5834\u898f\u6a21\u3092\u7b97\u51fa\u3057\u307e\u3057\u305f\u3002<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[100,141,160],"tags":[139,140,159720,159721],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u4e16\u754c\u5e02\u5834\uff082026\u5e74\u7248\uff09 \uff1a\u96fb\u6c17\u6a5f\u68b0\u5f0f\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u3001\u30d0\u30a4\u30dd\u30fc\u30e9\u5f0f\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf \uff1a\u5e02\u5834\u4e88\u6e2c\u30fb\u898f\u6a21\u30ec\u30dd\u30fc\u30c8<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.marketreport.jp\/research\/global-laparoscopic-morcellators-market-research-report-girc-078950\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u4e16\u754c\u5e02\u5834\uff082026\u5e74\u7248\uff09 \uff1a\u96fb\u6c17\u6a5f\u68b0\u5f0f\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u3001\u30d0\u30a4\u30dd\u30fc\u30e9\u5f0f\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf \uff1a\u5e02\u5834\u4e88\u6e2c\u30fb\u898f\u6a21\u30ec\u30dd\u30fc\u30c8\" \/>\n<meta property=\"og:description\" content=\"\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u4e16\u754c\u5e02\u5834\u30ec\u30dd\u30fc\u30c8\uff08Global Laparoscopic Morcellators Market\uff09\u3067\u306f\u3001\u30bb\u30b0\u30e1\u30f3\u30c8\u5225\u5e02\u5834\u898f\u6a21\uff08\u7a2e\u985e\u5225\uff1a\u96fb\u6c17\u6a5f\u68b0\u5f0f\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u3001\u30d0\u30a4\u30dd\u30fc\u30e9\u5f0f\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u3001\u7528\u9014\u5225\uff1a\u8179\u8154\u93e1\u4e0b\u5b50\u5bae\u6458\u51fa\u8853\u3001\u8179\u8154\u93e1\u4e0b\u80c6\u56a2\u6458\u51fa\u8853\u3001\u8179\u8154\u93e1\u4e0b\u814e\u81d3\u6458\u51fa\u8853\uff09\u3001\u4e3b\u8981\u5730\u57df\u3068\u56fd\u5225\u5e02\u5834\u898f\u6a21\u3001\u56fd\u5185\u5916\u306e\u4e3b\u8981\u30d7\u30ec\u30fc\u30e4\u30fc\u306e\u52d5\u5411\u3068\u5e02\u5834\u30b7\u30a7\u30a2\u3001\u8ca9\u58f2\u30c1\u30e3\u30cd\u30eb\u306a\u3069\u306e\u9805\u76ee\u306b\u3064\u3044\u3066\u8a73\u7d30\u306a\u5206\u6790\u3092\u884c\u3044\u307e\u3057\u305f\u3002\u5730\u57df\u30fb\u56fd\u5225\u5206\u6790\u3067\u306f\u3001\u5317\u7c73\u3001\u30a2\u30e1\u30ea\u30ab\u3001\u30ab\u30ca\u30c0\u3001\u30e1\u30ad\u30b7\u30b3\u3001\u30e8\u30fc\u30ed\u30c3\u30d1\u3001\u30c9\u30a4\u30c4\u3001\u30a4\u30ae\u30ea\u30b9\u3001\u30d5\u30e9\u30f3\u30b9\u3001\u30ed\u30b7\u30a2\u3001\u30a2\u30b8\u30a2\u592a\u5e73\u6d0b\u3001\u65e5\u672c\u3001\u4e2d\u56fd\u3001\u30a4\u30f3\u30c9\u3001\u97d3\u56fd\u3001\u6771\u5357\u30a2\u30b8\u30a2\u3001\u5357\u7c73\u3001\u4e2d\u6771\u3001\u30a2\u30d5\u30ea\u30ab\u306a\u3069\u3092\u5bfe\u8c61\u306b\u3057\u3066\u3001\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u5e02\u5834\u898f\u6a21\u3092\u7b97\u51fa\u3057\u307e\u3057\u305f\u3002\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.marketreport.jp\/research\/global-laparoscopic-morcellators-market-research-report-girc-078950\" \/>\n<meta property=\"og:site_name\" content=\"MarketReport.jp\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-25T02:27:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-21T09:16:04+00:00\" \/>\n<meta name=\"author\" content=\"marketreport.jp\" \/>\n<meta name=\"twitter:label1\" content=\"\u57f7\u7b46\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"marketreport.jp\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u63a8\u5b9a\u8aad\u307f\u53d6\u308a\u6642\u9593\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.marketreport.jp\/research\/global-laparoscopic-morcellators-market-research-report-girc-078950\",\"url\":\"https:\/\/www.marketreport.jp\/research\/global-laparoscopic-morcellators-market-research-report-girc-078950\",\"name\":\"\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u4e16\u754c\u5e02\u5834\uff082026\u5e74\u7248\uff09 \uff1a\u96fb\u6c17\u6a5f\u68b0\u5f0f\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u3001\u30d0\u30a4\u30dd\u30fc\u30e9\u5f0f\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf \uff1a\u5e02\u5834\u4e88\u6e2c\u30fb\u898f\u6a21\u30ec\u30dd\u30fc\u30c8\",\"isPartOf\":{\"@id\":\"https:\/\/www.marketreport.jp\/research\/#website\"},\"datePublished\":\"2022-08-25T02:27:52+00:00\",\"dateModified\":\"2026-07-21T09:16:04+00:00\",\"author\":{\"@id\":\"https:\/\/www.marketreport.jp\/research\/#\/schema\/person\/71c9fa2061f39928c2132639f3af3d96\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.marketreport.jp\/research\/global-laparoscopic-morcellators-market-research-report-girc-078950#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.marketreport.jp\/research\/global-laparoscopic-morcellators-market-research-report-girc-078950\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.marketreport.jp\/research\/global-laparoscopic-morcellators-market-research-report-girc-078950#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.marketreport.jp\/research\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u4e16\u754c\u5e02\u5834\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.marketreport.jp\/research\/#website\",\"url\":\"https:\/\/www.marketreport.jp\/research\/\",\"name\":\"MarketReport.jp\",\"description\":\"\u5e02\u5834\u8abf\u67fb\u30ec\u30dd\u30fc\u30c8\u30fb\u7523\u696d\u8cc7\u6599 \u7dcf\u5408\u8ca9\u58f2\u30b5\u30a4\u30c8 www.MarketReport.jp\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.marketreport.jp\/research\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ja\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.marketreport.jp\/research\/#\/schema\/person\/71c9fa2061f39928c2132639f3af3d96\",\"name\":\"marketreport.jp\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\/\/www.marketreport.jp\/research\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/400b7d2014baa2a24cf6cb7878fdaef0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/400b7d2014baa2a24cf6cb7878fdaef0?s=96&d=mm&r=g\",\"caption\":\"marketreport.jp\"},\"url\":\"https:\/\/www.marketreport.jp\/research\/author\/marketreport-jp\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u4e16\u754c\u5e02\u5834\uff082026\u5e74\u7248\uff09 \uff1a\u96fb\u6c17\u6a5f\u68b0\u5f0f\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u3001\u30d0\u30a4\u30dd\u30fc\u30e9\u5f0f\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf \uff1a\u5e02\u5834\u4e88\u6e2c\u30fb\u898f\u6a21\u30ec\u30dd\u30fc\u30c8","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.marketreport.jp\/research\/global-laparoscopic-morcellators-market-research-report-girc-078950","og_locale":"ja_JP","og_type":"article","og_title":"\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u4e16\u754c\u5e02\u5834\uff082026\u5e74\u7248\uff09 \uff1a\u96fb\u6c17\u6a5f\u68b0\u5f0f\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u3001\u30d0\u30a4\u30dd\u30fc\u30e9\u5f0f\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf \uff1a\u5e02\u5834\u4e88\u6e2c\u30fb\u898f\u6a21\u30ec\u30dd\u30fc\u30c8","og_description":"\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u4e16\u754c\u5e02\u5834\u30ec\u30dd\u30fc\u30c8\uff08Global Laparoscopic Morcellators Market\uff09\u3067\u306f\u3001\u30bb\u30b0\u30e1\u30f3\u30c8\u5225\u5e02\u5834\u898f\u6a21\uff08\u7a2e\u985e\u5225\uff1a\u96fb\u6c17\u6a5f\u68b0\u5f0f\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u3001\u30d0\u30a4\u30dd\u30fc\u30e9\u5f0f\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u3001\u7528\u9014\u5225\uff1a\u8179\u8154\u93e1\u4e0b\u5b50\u5bae\u6458\u51fa\u8853\u3001\u8179\u8154\u93e1\u4e0b\u80c6\u56a2\u6458\u51fa\u8853\u3001\u8179\u8154\u93e1\u4e0b\u814e\u81d3\u6458\u51fa\u8853\uff09\u3001\u4e3b\u8981\u5730\u57df\u3068\u56fd\u5225\u5e02\u5834\u898f\u6a21\u3001\u56fd\u5185\u5916\u306e\u4e3b\u8981\u30d7\u30ec\u30fc\u30e4\u30fc\u306e\u52d5\u5411\u3068\u5e02\u5834\u30b7\u30a7\u30a2\u3001\u8ca9\u58f2\u30c1\u30e3\u30cd\u30eb\u306a\u3069\u306e\u9805\u76ee\u306b\u3064\u3044\u3066\u8a73\u7d30\u306a\u5206\u6790\u3092\u884c\u3044\u307e\u3057\u305f\u3002\u5730\u57df\u30fb\u56fd\u5225\u5206\u6790\u3067\u306f\u3001\u5317\u7c73\u3001\u30a2\u30e1\u30ea\u30ab\u3001\u30ab\u30ca\u30c0\u3001\u30e1\u30ad\u30b7\u30b3\u3001\u30e8\u30fc\u30ed\u30c3\u30d1\u3001\u30c9\u30a4\u30c4\u3001\u30a4\u30ae\u30ea\u30b9\u3001\u30d5\u30e9\u30f3\u30b9\u3001\u30ed\u30b7\u30a2\u3001\u30a2\u30b8\u30a2\u592a\u5e73\u6d0b\u3001\u65e5\u672c\u3001\u4e2d\u56fd\u3001\u30a4\u30f3\u30c9\u3001\u97d3\u56fd\u3001\u6771\u5357\u30a2\u30b8\u30a2\u3001\u5357\u7c73\u3001\u4e2d\u6771\u3001\u30a2\u30d5\u30ea\u30ab\u306a\u3069\u3092\u5bfe\u8c61\u306b\u3057\u3066\u3001\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u5e02\u5834\u898f\u6a21\u3092\u7b97\u51fa\u3057\u307e\u3057\u305f\u3002","og_url":"https:\/\/www.marketreport.jp\/research\/global-laparoscopic-morcellators-market-research-report-girc-078950","og_site_name":"MarketReport.jp","article_published_time":"2022-08-25T02:27:52+00:00","article_modified_time":"2026-07-21T09:16:04+00:00","author":"marketreport.jp","twitter_misc":{"\u57f7\u7b46\u8005":"marketreport.jp","\u63a8\u5b9a\u8aad\u307f\u53d6\u308a\u6642\u9593":"2\u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.marketreport.jp\/research\/global-laparoscopic-morcellators-market-research-report-girc-078950","url":"https:\/\/www.marketreport.jp\/research\/global-laparoscopic-morcellators-market-research-report-girc-078950","name":"\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u4e16\u754c\u5e02\u5834\uff082026\u5e74\u7248\uff09 \uff1a\u96fb\u6c17\u6a5f\u68b0\u5f0f\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u3001\u30d0\u30a4\u30dd\u30fc\u30e9\u5f0f\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf \uff1a\u5e02\u5834\u4e88\u6e2c\u30fb\u898f\u6a21\u30ec\u30dd\u30fc\u30c8","isPartOf":{"@id":"https:\/\/www.marketreport.jp\/research\/#website"},"datePublished":"2022-08-25T02:27:52+00:00","dateModified":"2026-07-21T09:16:04+00:00","author":{"@id":"https:\/\/www.marketreport.jp\/research\/#\/schema\/person\/71c9fa2061f39928c2132639f3af3d96"},"breadcrumb":{"@id":"https:\/\/www.marketreport.jp\/research\/global-laparoscopic-morcellators-market-research-report-girc-078950#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.marketreport.jp\/research\/global-laparoscopic-morcellators-market-research-report-girc-078950"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.marketreport.jp\/research\/global-laparoscopic-morcellators-market-research-report-girc-078950#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.marketreport.jp\/research\/"},{"@type":"ListItem","position":2,"name":"\u8179\u8154\u93e1\u4e0b\u30e2\u30eb\u30bb\u30ec\u30fc\u30bf\u306e\u4e16\u754c\u5e02\u5834"}]},{"@type":"WebSite","@id":"https:\/\/www.marketreport.jp\/research\/#website","url":"https:\/\/www.marketreport.jp\/research\/","name":"MarketReport.jp","description":"\u5e02\u5834\u8abf\u67fb\u30ec\u30dd\u30fc\u30c8\u30fb\u7523\u696d\u8cc7\u6599 \u7dcf\u5408\u8ca9\u58f2\u30b5\u30a4\u30c8 www.MarketReport.jp","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.marketreport.jp\/research\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"ja"},{"@type":"Person","@id":"https:\/\/www.marketreport.jp\/research\/#\/schema\/person\/71c9fa2061f39928c2132639f3af3d96","name":"marketreport.jp","image":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/www.marketreport.jp\/research\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/400b7d2014baa2a24cf6cb7878fdaef0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/400b7d2014baa2a24cf6cb7878fdaef0?s=96&d=mm&r=g","caption":"marketreport.jp"},"url":"https:\/\/www.marketreport.jp\/research\/author\/marketreport-jp"}]}},"_links":{"self":[{"href":"https:\/\/www.marketreport.jp\/research\/wp-json\/wp\/v2\/posts\/678485"}],"collection":[{"href":"https:\/\/www.marketreport.jp\/research\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.marketreport.jp\/research\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.marketreport.jp\/research\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.marketreport.jp\/research\/wp-json\/wp\/v2\/comments?post=678485"}],"version-history":[{"count":0,"href":"https:\/\/www.marketreport.jp\/research\/wp-json\/wp\/v2\/posts\/678485\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.marketreport.jp\/research\/wp-json\/wp\/v2\/media?parent=678485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.marketreport.jp\/research\/wp-json\/wp\/v2\/categories?post=678485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.marketreport.jp\/research\/wp-json\/wp\/v2\/tags?post=678485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}